{"id":280,"date":"2011-12-12T01:18:30","date_gmt":"2011-12-12T00:18:30","guid":{"rendered":"http:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng.gif"},"modified":"2011-12-12T01:18:30","modified_gmt":"2011-12-12T00:18:30","slug":"ngramviewer_todsuenden_dt_eng","status":"inherit","type":"attachment","link":"https:\/\/nueckel.at\/blog\/der-ngram-viewer-macht-mehr-spas-als-er-klingt\/ngramviewer_todsuenden_dt_eng\/","title":{"rendered":"ngramviewer_todsuenden_dt_eng"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng.gif'><img loading=\"lazy\" width=\"300\" height=\"228\" src=\"https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng-500x380.gif\" class=\"attachment-medium size-medium\" alt=\"Ngram Viewer zeigt die sieben Tods\u00fcnden\" decoding=\"async\" srcset=\"https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng-500x380.gif 500w, https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng-100x76.gif 100w, https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng-393x300.gif 393w, https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng.gif 752w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Die sieben Tods\u00fcnden zwischen 1900 und 2000<\/p>\n"},"alt_text":"Ngram Viewer zeigt die sieben Tods\u00fcnden","media_type":"image","mime_type":"image\/gif","media_details":{"width":"752","height":"573","hwstring_small":"height='96' width='125'","file":"ngramviewer_todsuenden_dt_eng.gif","sizes":{"thumbnail":{"file":"ngramviewer_todsuenden_dt_eng-100x76.gif","width":"100","height":"76","source_url":"https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng-100x76.gif"},"medium":{"file":"ngramviewer_todsuenden_dt_eng-500x380.gif","width":"500","height":"380","source_url":"https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng-500x380.gif"},"post-thumbnail":{"file":"ngramviewer_todsuenden_dt_eng-752x288.gif","width":"752","height":"288","source_url":"https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng-752x288.gif"},"large-feature":{"file":"ngramviewer_todsuenden_dt_eng-752x288.gif","width":"752","height":"288","source_url":"https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng-752x288.gif"},"small-feature":{"file":"ngramviewer_todsuenden_dt_eng-393x300.gif","width":"393","height":"300","source_url":"https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng-393x300.gif"},"full":{"file":"ngramviewer_todsuenden_dt_eng.gif","width":752,"height":573,"mime_type":"image\/gif","source_url":"https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng.gif"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":278,"source_url":"https:\/\/nueckel.at\/blog\/wp-content\/uploads\/ngramviewer_todsuenden_dt_eng.gif","_links":{"self":[{"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/media\/280"}],"collection":[{"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/comments?post=280"}]}}