{"id":6542,"date":"2019-02-25T11:37:51","date_gmt":"2019-02-25T11:37:51","guid":{"rendered":"https:\/\/nueckel.at\/blog\/?p=6542"},"modified":"2019-07-04T12:01:19","modified_gmt":"2019-07-04T12:01:19","slug":"ein-literaturfuehrer-fuer-die-oekosoziale-transformation","status":"publish","type":"post","link":"https:\/\/nueckel.at\/blog\/ein-literaturfuehrer-fuer-die-oekosoziale-transformation\/","title":{"rendered":"Ein Literaturf\u00fchrer f\u00fcr die \u00f6kosoziale Transformation"},"content":{"rendered":"<p>Den folgenden Text habe ich beim Open Stage der Abschlu\u00dfveranstaltung zur Ausstellung &#8222;Endlich Wachstum&#8220; am 24. Februar 2019 im Schweitzer Haus, Wien vorgetragen.<!--more--><\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>Transformation.<br \/>\nVon Ausbeutung, Gier, Katastrophen zu Gutem Leben f\u00fcr alle.<br \/>\nVon schlechtem Jetzt zu Guter Zukunft.<br \/>\nVon hier nach dort.<\/p>\n<p>Transformation: eine Reise von hier nach Eutopia*.<\/p>\n<p><i>(*Ein idealer Ort des Wohlstandes, der Gesundheit und des Gl\u00fccks ist das, was wir wollen. Im Gegensatz zu Utopia, der unerreichbare Nicht-Ort.)<\/i><\/p>\n<p>Sind B\u00fccher zur Transformation also Reisef\u00fchrer?<br \/>\nK\u00f6nnten, sollten diese B\u00fccher den Kapiteln eines Reisef\u00fchrers entsprechen?<br \/>\nSo gesehen: Was gibt es? Was fehlt?<\/p>\n<h2>Kapitel 1: B\u00fccher der Bestandsaufnahme<\/h2>\n<p>Zahlen, Daten, Fakten,<br \/>\ngeschrieben von Menschen der Wissenschaft und des Journalismus.<\/p>\n<p><i>Stil:<\/i><br \/>\nSchulbuch \u2013 viel Text, viele Grafiken, wenig Bilder.<\/p>\n<p><i>Wie f\u00fchlt man sich nach dem Zuklappen des Kapitels?<\/i><br \/>\nDeprimiert, aber gescheit.<br \/>\nSo gescheit, dass man es anderen erz\u00e4hlt, ihnen unter die Nase reibt.<br \/>\nBis sie genauso deprimiert sind.<\/p>\n<p><i>Wie n\u00fctzlich ist es f\u00fcr die Reise?<\/i><br \/>\nMan findet Gleichgesinnte.<\/p>\n<p><i>Fazit:<\/i> ungew\u00f6hnlich.<br \/>\nIn keinem konventionellen Reisef\u00fchrer findet sich ein Abschnitt zur Frage \u201eWarum abreisen?\u201c.<\/p>\n<h2>Kapitel 2: Die Welt, wenn wir so weitermachen<\/h2>\n<p>Dystopische Zukunftsszenarien,<br \/>\ngeschrieben von ZukunftsforscherInnen.<\/p>\n<p><i>Stil:<\/i><br \/>\nreicht von n\u00fcchterner Dokumentation zu rei\u00dferischen Sci-Fi-Blockbustern.<\/p>\n<p><i>Wie f\u00fchlt man sich nach dem Zuklappen des Kapitels?<\/i><br \/>\nPanisch. Schwankend zwischen Flucht und Starre.<br \/>\nBis man eine Entscheidung treffen kann,<br \/>\nkratzt man unter Tr\u00e4nen seine Ganja- und Blauburgunderreste zusammen,<br \/>\ngreift zu Schokolade und loggt sich bei Netflix ein.<\/p>\n<p><i>Wie n\u00fctzlich ist es f\u00fcr die Reise?<\/i><br \/>\nGerade noch Gleichgesinnte verabschieden sich:<br \/>\nVergi\u00df es, ich flieg auf die Malediven, solange ich noch kann!<\/p>\n<p><i>Fazit:<\/i> ungeeignet.<br \/>\nEigentlich ein Anti-Reisef\u00fchrer<\/p>\n<h2>Kapitel 3: Von Urban Gardening zu Zeit-Geld-Systemen<\/h2>\n<p>Praktische Informationen,<br \/>\ngeschrieben von Autodidakten und Theoretikern.<\/p>\n<p><i>Stil:<\/i><br \/>\nHandbuch \u2013 mit Schritt-f\u00fcr-Schritt-Anleitungen, Erfahrungsberichten und pers\u00f6nlichen Tipps.<\/p>\n<p><i>Wie f\u00fchlt man sich nach dem Zuklappen des Kapitels?<\/i><br \/>\nTheoretisch topinformiert.<br \/>\nAbreisebereit. Aktiviert. Angestachelt.<br \/>\nEs geht ja doch! Mehr davon!<\/p>\n<p><i>Wie n\u00fctzlich ist es f\u00fcr die Reise?<\/i><br \/>\nTheoretisch topwichtig.<br \/>\nPraktisch hohe Verzettelungsgefahr:<br \/>\n25 Methoden, die eigene Tomatenernte zu verarbeiten, um damit \u00fcber den Winter zu kommen.<br \/>\n25 soziale Ans\u00e4tze und \u00f6konomische Konzepte, um den Diskurs anzukurbeln.<\/p>\n<p><i>Fazit:<\/i><br \/>\ntheoretisch praktisch.<br \/>\nDas sind die nie fehlenden zw\u00f6lf Seiten auf hellblauem oder gelbem Papier am Anfang oder am Ende eines konventionellen Reisef\u00fchrers.<br \/>\nWo sich \u00fcbrigens unter \u201eAnreise\u201c immer mehr als ein Transportmittel findet &#8230;<\/p>\n<h2>Kapitel 4: Bilder der Zukunft<\/h2>\n<p>Die sozialen, wirtschaftlichen und kulturellen M\u00f6glichkeiten nach der Transformation,<br \/>\ngeschrieben von Vision\u00e4rInnen<\/p>\n<p><i>Stil:<\/i><br \/>\ndie ausf\u00fchrliche Beschreibung eines Filmsettings<\/p>\n<p><i>Wie f\u00fchlt man sich nach dem Zuklappen des Kapitels?<\/i><br \/>\nAbwesend. Keine Interesse an Spiel, Ablenkung, Unsinnigkeiten.<br \/>\nDie Gedanken kreisen:<br \/>\nWas werde ich dort essen? Wo werde ich schlafen? Was schau ich mir an?<br \/>\nWas mache ich dort den ganzen Tag?<\/p>\n<p><i>Wie n\u00fctzlich ist es f\u00fcr die Reise?<\/i><br \/>\nEs wird konkret. \u201eDa will ich unbedingt hin!\u201c.<br \/>\nReisestrecke, Zwischenstops, Schwerpunkte, Reisemotto.<\/p>\n<p><i>Fazit:<\/i><br \/>\nessentiell.<br \/>\nDas ist der fette, bunte Mittelteil jedes Reisef\u00fchrers mit den Orten und Sehensw\u00fcrdigkeiten, gewidmet der Vielfalt und Sch\u00f6nheit.<\/p>\n<h2>Kapitel 5: W\u00f6rterbuch<\/h2>\n<p>Die wichtigsten Begriffe und Redewendungen.<\/p>\n<p><i>Stil:<\/i><br \/>\nweniger wie ein normales W\u00f6rterbuch, mehr wie eine Liste Un\u00fcbersetzbarer W\u00f6rter<\/p>\n<p><i>Wie f\u00fchlt man sich nach dem Zuklappen des Kapitels?<\/i><br \/>\nWahrscheinlich unn\u00f6tig besorgt um die richtige Aussprache.<br \/>\nErfahrungsgem\u00e4\u00df sind die Einheimischen freundlich und hilfsbereit.<\/p>\n<p><i>Wie n\u00fctzlich ist es f\u00fcr die Reise?<\/i><br \/>\nAndere L\u00e4nder, andere Sitten, andere Sprache.<\/p>\n<p><i>Fazit:<\/i><br \/>\nUnverzichtbar.<\/p>\n<h2>Kapitel 6: Geschichten<\/h2>\n<p>Dem Setting wird Leben eingehaucht,<br \/>\ngeschrieben von Erz\u00e4hlerInnen, Romanciers.<\/p>\n<p><i>Stil:<\/i><br \/>\nBelletristik<\/p>\n<p><i>Wie f\u00fchlt man sich nach dem Zuklappen des Kapitels?<\/i><br \/>\nErgriffen, sehns\u00fcchtig, voller Fernweh.<br \/>\nSo k\u00f6nnte sich diese Welt anf\u00fchlen.<br \/>\nSo k\u00f6nnte ich leben.<\/p>\n<p><i>Wie n\u00fctzlich ist es f\u00fcr die Reise?<\/i><br \/>\nWenn Romane wie 1984 uns nach 2019 gebracht haben? &#8230;<\/p>\n<p><i>Fazit:<\/i><br \/>\nNicht der sachliche Reisef\u00fchrer bringt uns in ein anderes Land!<br \/>\nDer Krimi von Donna Leon bringt uns nach Venedig.<br \/>\nDer Western von Karl May nach Kroatien.<br \/>\nDie Liebesgeschichte von Rosamunde Pilcher nach Cornwall.<br \/>\nDie Satire von Ephraim Kishon nach Israel.<br \/>\nDas Kinderbuch von Astrid Lindgren nach Schweden.<br \/>\nDer Comic von Rene Goscinny bringt uns nach Gallien. Oder nach Rom, \u00c4gypten, Spanien, Korsika, ins Morgenland, zu den Goten, den Briten, Normannen, Schweizern, Belgiern und Pikten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Den folgenden Text habe ich beim Open Stage der Abschlu\u00dfveranstaltung zur Ausstellung &#8222;Endlich Wachstum&#8220; am 24. Februar 2019 im Schweitzer Haus, Wien vorgetragen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[182],"_links":{"self":[{"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/posts\/6542"}],"collection":[{"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/comments?post=6542"}],"version-history":[{"count":3,"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/posts\/6542\/revisions"}],"predecessor-version":[{"id":6545,"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/posts\/6542\/revisions\/6545"}],"wp:attachment":[{"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/media?parent=6542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/categories?post=6542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nueckel.at\/blog\/wp-json\/wp\/v2\/tags?post=6542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}